{"id":1199,"date":"2021-07-13T11:00:51","date_gmt":"2021-07-13T09:00:51","guid":{"rendered":"https:\/\/sme-groupe.com\/?page_id=1199"},"modified":"2026-09-01T16:49:16","modified_gmt":"2026-09-01T14:49:16","slug":"mentions-legales","status":"publish","type":"page","link":"https:\/\/sme-groupe.com\/en\/mentions-legales\/","title":{"rendered":"Mentions l\u00e9gales"},"content":{"rendered":"<h2>Edition et H\u00e9bergement<\/h2>\n<p>SME-Groupe.com est le site Internet institutionnel de la soci\u00e9t\u00e9 Soleil Mer Evasion. Il est \u00e9dit\u00e9 par la soci\u00e9t\u00e9 Soleil Mer Evasion, soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9e au capital de 8000 euros.<br \/>\nLe si\u00e8ge social de la soci\u00e9t\u00e9 Soleil Mer Evasion est situ\u00e9 au 21 rue de la Belle Feuille \u00e0 Boulogne Billancourt 92100.<br \/>\nLa soci\u00e9t\u00e9 Soleil Mer Evasion est enregistr\u00e9e au Registre du Commerce et des Soci\u00e9t\u00e9s de Nanterre sous le num\u00e9ro de SIRET 411 107 675 00034<br \/>\nLe site Internet SME-Groupe.com est h\u00e9berg\u00e9 par la soci\u00e9t\u00e9 OVH SAS, inscrite au RCS de Lille M\u00e9tropole au num\u00e9ro B424 761 419, 2 rue Kellermann 59100 Roubaix. Le site internet SME-Groupe.com a \u00e9t\u00e9 r\u00e9alis\u00e9 par fiatte.com<\/p>\n<h2>Propri\u00e9t\u00e9 intellectuelle<\/h2>\n<p>Le contenu du site SME-Groupe.com notamment les textes, commentaires, illustrations et images sont la propri\u00e9t\u00e9 de la soci\u00e9t\u00e9 Soleil Mer Evasion ou le cas \u00e9ch\u00e9ant de ses partenaires, et sont prot\u00e9g\u00e9s par les lois fran\u00e7aises et internationales au titre de la propri\u00e9t\u00e9 intellectuelle et ce pour le monde entier. La reproduction ou repr\u00e9sentation, int\u00e9grale ou partielle, des pages, des donn\u00e9es et de tout autre \u00e9l\u00e9ment constitutif au site SME-Groupe.com par quelque proc\u00e9d\u00e9 ou support que ce soit, est strictement interdite et est susceptible de constituer sans autorisation de Soleil Mer Evasion un d\u00e9lit de contrefa\u00e7on.<\/p>","protected":false},"excerpt":{"rendered":"<p>Edition et H\u00e9bergement SME-Groupe.com est le site Internet institutionnel de la soci\u00e9t\u00e9 Soleil Mer Evasion. Il est \u00e9dit\u00e9 par la soci\u00e9t\u00e9 Soleil Mer Evasion, soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9e au capital de 8000 euros. Le si\u00e8ge social de la soci\u00e9t\u00e9 Soleil Mer Evasion est situ\u00e9 au 21 rue de la Belle Feuille \u00e0 Boulogne Billancourt 92100. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1199","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/sme-groupe.com\/en\/wp-json\/wp\/v2\/pages\/1199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sme-groupe.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sme-groupe.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sme-groupe.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sme-groupe.com\/en\/wp-json\/wp\/v2\/comments?post=1199"}],"version-history":[{"count":4,"href":"https:\/\/sme-groupe.com\/en\/wp-json\/wp\/v2\/pages\/1199\/revisions"}],"predecessor-version":[{"id":2785,"href":"https:\/\/sme-groupe.com\/en\/wp-json\/wp\/v2\/pages\/1199\/revisions\/2785"}],"wp:attachment":[{"href":"https:\/\/sme-groupe.com\/en\/wp-json\/wp\/v2\/media?parent=1199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}